{"id":38,"date":"2016-12-11T14:57:55","date_gmt":"2016-12-11T13:57:55","guid":{"rendered":"https:\/\/easytaxischiphol.nl\/?page_id=38"},"modified":"2025-03-04T03:51:08","modified_gmt":"2025-03-04T02:51:08","slug":"faq","status":"publish","type":"page","link":"https:\/\/easytaxischiphol.nl\/pt\/faq\/","title":{"rendered":"veelgestelde vragen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"faq-page.php","meta":{"footnotes":""},"class_list":["post-38","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>veelgestelde vragen - Easy Taxi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/easytaxischiphol.nl\/en\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"veelgestelde vragen - Easy Taxi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/easytaxischiphol.nl\/en\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Easy Taxi\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T02:51:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/easytaxischiphol.nl\\\/en\\\/faq\\\/\",\"url\":\"https:\\\/\\\/easytaxischiphol.nl\\\/en\\\/faq\\\/\",\"name\":\"veelgestelde vragen - Easy Taxi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/easytaxischiphol.nl\\\/#website\"},\"datePublished\":\"2016-12-11T13:57:55+00:00\",\"dateModified\":\"2025-03-04T02:51:08+00:00\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/easytaxischiphol.nl\\\/en\\\/faq\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/easytaxischiphol.nl\\\/#website\",\"url\":\"https:\\\/\\\/easytaxischiphol.nl\\\/\",\"name\":\"Easy Taxi\",\"description\":\"En nog een WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/easytaxischiphol.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"veelgestelde vragen - Easy Taxi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/easytaxischiphol.nl\/en\/faq\/","og_locale":"pt_PT","og_type":"article","og_title":"veelgestelde vragen - Easy Taxi","og_url":"https:\/\/easytaxischiphol.nl\/en\/faq\/","og_site_name":"Easy Taxi","article_modified_time":"2025-03-04T02:51:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/easytaxischiphol.nl\/en\/faq\/","url":"https:\/\/easytaxischiphol.nl\/en\/faq\/","name":"veelgestelde vragen - Easy Taxi","isPartOf":{"@id":"https:\/\/easytaxischiphol.nl\/#website"},"datePublished":"2016-12-11T13:57:55+00:00","dateModified":"2025-03-04T02:51:08+00:00","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/easytaxischiphol.nl\/en\/faq\/"]}]},{"@type":"WebSite","@id":"https:\/\/easytaxischiphol.nl\/#website","url":"https:\/\/easytaxischiphol.nl\/","name":"Easy Taxi","description":"En nog een WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/easytaxischiphol.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/easytaxischiphol.nl\/pt\/wp-json\/wp\/v2\/pages\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easytaxischiphol.nl\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/easytaxischiphol.nl\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/easytaxischiphol.nl\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/easytaxischiphol.nl\/pt\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":31,"href":"https:\/\/easytaxischiphol.nl\/pt\/wp-json\/wp\/v2\/pages\/38\/revisions"}],"predecessor-version":[{"id":965,"href":"https:\/\/easytaxischiphol.nl\/pt\/wp-json\/wp\/v2\/pages\/38\/revisions\/965"}],"wp:attachment":[{"href":"https:\/\/easytaxischiphol.nl\/pt\/wp-json\/wp\/v2\/media?parent=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}